{"id":6250,"date":"2025-11-28T16:20:26","date_gmt":"2025-11-28T08:20:26","guid":{"rendered":"https:\/\/kailion.ltd\/?post_type=product&#038;p=6250"},"modified":"2025-11-28T16:20:27","modified_gmt":"2025-11-28T08:20:27","slug":"13-5m-aerial-work-platform-faw","status":"publish","type":"product","link":"https:\/\/kailion.ltd\/fr\/13-5m-aerial-work-platform-faw.html","title":{"rendered":"Plateforme \u00e9l\u00e9vatrice mobile de 13,5 m FAW"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-6252\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_01.webp\" alt=\"\" width=\"1234\" height=\"1601\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_01.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_01-231x300.webp 231w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_01-768x996.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_01-9x12.webp 9w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_01-600x778.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_01-150x195.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<h1 style=\"text-align: center;\">PARAM\u00c8TRES DU PRODUIT<\/h1>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-6253\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_03.webp\" alt=\"\" width=\"1234\" height=\"469\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_03.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_03-300x114.webp 300w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_03-768x292.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_03-18x7.webp 18w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_03-600x228.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_03-150x57.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<h2 style=\"text-align: center;\"><strong>\u00a0 Plateforme \u00e9l\u00e9vatrice mobile de 13,5 m FAW <\/strong><\/h2>\n<table>\n<tbody>\n<tr>\n<td width=\"85\"><strong>projet<\/strong><\/td>\n<td width=\"307\"><strong>Descriptions<\/strong><\/td>\n<td width=\"307\"><strong>Caract\u00e9ristiques<\/strong><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\" width=\"85\"><strong>G\u00e9n\u00e9ral<\/strong><\/td>\n<td width=\"307\"><strong>Dimensions hors tout (mm)<\/strong><\/td>\n<td width=\"307\"><strong>5990*1980*2950<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Masse totale (kg)<\/strong><\/td>\n<td width=\"307\"><strong>4495<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Curb weight(Kg)<\/strong><\/td>\n<td width=\"307\"><strong>4365<\/strong><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"6\" width=\"85\"><strong>Corps<\/strong><\/td>\n<td width=\"307\"><strong>Hauteur de fonctionnement maximale (m)<\/strong><\/td>\n<td width=\"307\"><strong>13.5<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Port\u00e9e maximale de fonctionnement (m)<\/strong><\/td>\n<td width=\"307\"><strong>6.5<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>angle de rotation<\/strong><\/td>\n<td width=\"307\"><strong>360\u00b0<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Dimensions du godet de travail (mm)<\/strong><\/td>\n<td width=\"307\"><strong>1080X620X1150\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Mat\u00e9riaux pour godet de travail<\/strong><\/td>\n<td width=\"307\"><strong>Acier inoxydable haute r\u00e9sistance<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>charge utile du godet (kg)<\/strong><\/td>\n<td width=\"307\"><strong>200<\/strong><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"6\" width=\"85\"><strong>Ch\u00e2ssis<\/strong><\/p>\n<p>&nbsp;<\/td>\n<td width=\"307\"><strong>Marque du ch\u00e2ssis<\/strong><\/td>\n<td width=\"307\"><strong>CLA<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Formulaire de conducteur<\/strong><\/td>\n<td width=\"307\"><strong>4*2<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Volant<\/strong><\/td>\n<td width=\"307\"><strong>Conduite \u00e0 gauche<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Marque et mod\u00e8le du moteur<\/strong><\/td>\n<td width=\"307\"><strong>Q23-115E60<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Puissance maximale du moteur (kW)<\/strong><\/td>\n<td width=\"307\"><strong>85<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"307\"><strong>Bo\u00eete de vitesse<\/strong><\/td>\n<td width=\"307\"><strong>5-speed transmission<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1 style=\"text-align: center;\">AVANTAGES DU V\u00c9HICULE<\/h1>\n<h2 style=\"text-align: center;\">EXCELLENTES CONFIGURATIONS DE S\u00c9CURIT\u00c9<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-6254\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05.webp\" alt=\"\" width=\"1234\" height=\"1806\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05-205x300.webp 205w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05-700x1024.webp 700w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05-768x1124.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05-8x12.webp 8w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05-600x878.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_05-150x219.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<p>1. Deux v\u00e9rins de levage hydrauliques : Les deux v\u00e9rins sont soumis \u00e0 une contrainte sym\u00e9trique, ce qui permet d'\u00e9viter les d\u00e9formations structurelles caus\u00e9es par une charge excentr\u00e9e unilat\u00e9rale et de r\u00e9duire les vibrations de la plateforme.<br \/>\n2. Soupape d'\u00e9quilibrage : elle permet de maintenir la charge, de contr\u00f4ler la vitesse et d'\u00e9viter les pertes et les chutes de charge.<br \/>\n3. Structure pentagonale : elle permet d'obtenir un \u00e9quilibre entre haute r\u00e9sistance et l\u00e9g\u00e8ret\u00e9.<br \/>\n4. R\u00e9servoir d'huile hydraulique : ses fonctions sont de stocker l'huile, de dissiper la chaleur, de pr\u00e9cipiter les impuret\u00e9s et de s\u00e9parer l'air.<br \/>\n5. Radiateur : il emp\u00eache la temp\u00e9rature de l'huile d'\u00eatre trop \u00e9lev\u00e9e, \u00e9vite la d\u00e9formation et l'endommagement des composants cl\u00e9s et am\u00e9liore la stabilit\u00e9, la pr\u00e9cision et l'efficacit\u00e9 du fonctionnement.<\/p>\n<blockquote>\n<h1 style=\"text-align: center;\">CONCEPTION DE CH\u00c2SSIS STABLE<\/h1>\n<\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6255\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_07.webp\" alt=\"\" width=\"1234\" height=\"1646\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_07.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_07-225x300.webp 225w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_07-768x1025.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_07-9x12.webp 9w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_07-600x801.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_07-150x200.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<p>1.Chassis outriggers: They provide stable support, enhance the load &#8211; bearingcapacity, and adapt to complex terrains.ICk<br \/>\n2. Jauge de niveau des stabilisateurs : elle mesure avec pr\u00e9cision le niveau des stabilisateurs, garantissant ainsi que l'\u00e9quipement reste dans un \u00e9tat stable pendant son fonctionnement.<\/p>\n<h1 style=\"text-align: center;\">SIMPLE D'UTILISATION<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6256\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_09.webp\" alt=\"\" width=\"1234\" height=\"487\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_09.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_09-300x118.webp 300w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_09-768x303.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_09-18x7.webp 18w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_09-600x237.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_09-150x59.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<p>User &#8211; friendly control panel(touch screen\/joystick), with a short trainingcycle and simple operation.<\/p>\n<h1 style=\"text-align: center;\">CONCEPTION CONVIVIALE<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6257\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_10.webp\" alt=\"\" width=\"1234\" height=\"1103\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_10.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_10-300x268.webp 300w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_10-768x686.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_10-13x12.webp 13w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_10-600x536.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_10-150x134.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<p>1. Si\u00e8ge conducteur<br \/>\n2. Chambre de chauffage ext\u00e9rieure<br \/>\n3. Roues tampons sous le bras<br \/>\n4. Crochets sous le bras<\/p>\n<h1 style=\"text-align: center;\">DISPOSITIFS DE PROTECTION MULTIPLES<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6258\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_12.webp\" alt=\"\" width=\"1234\" height=\"925\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_12.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_12-300x225.webp 300w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_12-768x576.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_12-16x12.webp 16w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_12-600x450.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_12-150x112.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<p>1. 360 &#8211; degree turntable fault alarm<br \/>\n2. Bouton d'arr\u00eat d'urgence<br \/>\n3. Garde-corps pour travaux en hauteur<br \/>\n4. Ceinture de s\u00e9curit\u00e9 pour le travail en hauteur<\/p>\n<h1 style=\"text-align: center;\">AUTRES D\u00c9TAILS<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6259\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_14.webp\" alt=\"\" width=\"1234\" height=\"1009\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_14.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_14-300x245.webp 300w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_14-768x628.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_14-15x12.webp 15w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_14-600x491.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_14-150x123.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<p>1. Enroulement des tuyaux hydrauliques<br \/>\n2. Feux de signalisation des stabilisateurs<br \/>\n3. D\u00e9tecteur de vitesse du vent<br \/>\n4. Bo\u00eete \u00e0 outils en acier inoxydable 304 5. Treuil<\/p>\n<h1 style=\"text-align: center;\">PROCESSUS DE PRODUCTION<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6260\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16.webp\" alt=\"\" width=\"1234\" height=\"2662\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16-139x300.webp 139w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16-475x1024.webp 475w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16-768x1657.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16-712x1536.webp 712w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16-6x12.webp 6w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16-600x1294.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_16-150x324.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6261\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17.webp\" alt=\"\" width=\"1234\" height=\"2674\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17-138x300.webp 138w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17-473x1024.webp 473w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17-768x1664.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17-709x1536.webp 709w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17-6x12.webp 6w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17-600x1300.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_17-150x325.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<p>1. Soudage \u00e0 fl\u00e8che t\u00e9lescopique<br \/>\n2. Soudage \u00e0 la fl\u00e8che<br \/>\n3. Soudage par poutre auxiliaire<br \/>\n4. Installez le ch\u00e2ssis sur le cadre de la poutre auxiliaire<br \/>\n5. Installez la plaque inf\u00e9rieure sur la base<br \/>\n6. Installez le bras de travail sur le ch\u00e2ssis<br \/>\n7. Installez le panier de travail et les autres accessoires.<br \/>\n8. Ach\u00e8vement de l'installation de la superstructure du v\u00e9hicule<\/p>\n<h1 style=\"text-align: center;\">SC\u00c9NARIOS D'APPLICATION<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6262\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19.webp\" alt=\"\" width=\"1234\" height=\"3465\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-107x300.webp 107w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-365x1024.webp 365w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-768x2156.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-547x1536.webp 547w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-729x2048.webp 729w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-4x12.webp 4w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-600x1685.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_19-150x421.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<h1 style=\"text-align: center;\">EMBALLAGE ET TRANSPORT<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6263\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21.webp\" alt=\"\" width=\"1234\" height=\"1724\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21-215x300.webp 215w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21-733x1024.webp 733w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21-768x1073.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21-9x12.webp 9w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21-600x838.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2025\/11\/\u9ad8\u7a7a\u8f66\u8be6\u60c5\u9875_21-150x210.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>PRODUCT PARAMETERS \u00a0 13.5m Aerial Work Platform FAW project Descriptions Specifications General Overall dimensions(mm) 5990*1980*2950 Total mass(Kg) 4495 Curb weight(Kg)<\/p>","protected":false},"featured_media":6264,"template":"","meta":[],"product_brand":[221],"product_cat":[172],"product_tag":[264,265,325],"class_list":{"0":"post-6250","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-faw","7":"product_cat-insulated-bucket-truck","8":"product_tag-truck-mounted-aerial-lifts","9":"product_tag-bucket-truck","10":"product_tag-13-5m","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product\/6250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product\/6250\/revisions"}],"predecessor-version":[{"id":6270,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product\/6250\/revisions\/6270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/media\/6264"}],"wp:attachment":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/media?parent=6250"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product_brand?post=6250"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product_cat?post=6250"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product_tag?post=6250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}