{"id":7601,"date":"2026-01-24T14:19:18","date_gmt":"2026-01-24T06:19:18","guid":{"rendered":"https:\/\/kailion.ltd\/?post_type=product&#038;p=7601"},"modified":"2026-07-04T15:50:46","modified_gmt":"2026-07-04T07:50:46","slug":"asphalt-distributor-10000l-shacman","status":"publish","type":"product","link":"https:\/\/kailion.ltd\/fr\/asphalt-distributor-10000l-shacman.html","title":{"rendered":"R\u00e9pandeuse de liant 10m\u00b3 SHACMAN"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7603\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15.webp\" alt=\"\" width=\"1234\" height=\"1617\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15-229x300.webp 229w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15-782x1024.webp 782w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15-768x1006.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15-9x12.webp 9w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15-600x786.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_01-15-150x197.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<h2 style=\"text-align: center;\">PARAM\u00c8TRES DU PRODUIT<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-7604\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_03-16.webp\" alt=\"\" width=\"1234\" height=\"489\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_03-16.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_03-16-300x119.webp 300w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_03-16-768x304.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_03-16-18x7.webp 18w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_03-16-600x238.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/1\u4ea7\u54c1\u6d77\u62a5_03-16-150x59.webp 150w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/p>\n<h1 style=\"text-align: center;\">R\u00e9pandeuse de liant 10m\u00b3 SHACMAN<\/h1>\n<table>\n<tbody>\n<tr>\n<td width=\"79\"><strong>projet<\/strong><\/td>\n<td width=\"319\"><strong>Descriptions<\/strong><\/td>\n<td width=\"288\"><strong>Caract\u00e9ristiques<\/strong><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\" width=\"79\"><strong>Basique<\/strong><\/td>\n<td width=\"319\"><strong>Dimensions hors tout (mm)<\/strong><\/td>\n<td width=\"288\"><strong>7930\u00d72550\u00d73550<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>poids \u00e0 vide (kg)<\/strong><\/td>\n<td width=\"288\"><strong>9120<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Capacit\u00e9 de charge (kg)<\/strong><\/td>\n<td width=\"288\"><strong>8970<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Masse totale (kg)<\/strong><\/td>\n<td width=\"288\"><strong>18000<\/strong><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\" width=\"79\"><strong>Corps<\/strong><\/td>\n<td width=\"319\"><strong>Volume total (L)<\/strong><\/td>\n<td width=\"288\"><strong>10000<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Mat\u00e9riau du r\u00e9servoir<\/strong><\/td>\n<td width=\"288\"><strong>Q235<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Syst\u00e8me de contr\u00f4le<\/strong><\/td>\n<td width=\"288\"><strong>syst\u00e8me de contr\u00f4le PLC<\/strong><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"8\" width=\"79\"><strong>Ch\u00e2ssis<\/strong><\/p>\n<p>&nbsp;<\/td>\n<td width=\"319\"><strong>Marque du ch\u00e2ssis<\/strong><\/td>\n<td width=\"288\"><strong>Shacman<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Formulaire de conduite<\/strong><\/td>\n<td width=\"288\"><strong>4*2<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Volant<\/strong><\/td>\n<td width=\"288\"><strong>Conduite \u00e0 gauche<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Marque et mod\u00e8le du moteur<\/strong><\/td>\n<td width=\"288\"><strong>YCS04200-68<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Puissance maximale du moteur (kW)<\/strong><\/td>\n<td width=\"288\"><strong>147<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Normes d&#039;\u00e9mission<\/strong><\/td>\n<td width=\"288\"><strong>Euro 6<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Bo\u00eete de vitesse<\/strong><\/td>\n<td width=\"288\"><strong>Fast 8 speed forward 1 reverse<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"319\"><strong>Essieu avant\/arri\u00e8re(t)<\/strong><\/td>\n<td width=\"288\"><strong>6.5\/11.5<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: center;\">AVANTAGES DU V\u00c9HICULE<\/h2>\n<h5 style=\"text-align: center;\">SYST\u00c8ME DE DIFFUSION INTELLIGENT ET PR\u00c9CIS<\/h5>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-7560\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_05.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_05.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_05-169x300.webp 169w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_05-578x1024.webp 578w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_05-768x1360.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_05-7x12.webp 7w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_05-600x1063.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_05-150x266.webp 150w\" alt=\"\" width=\"1234\" height=\"2185\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7561\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_06.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_06.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_06-154x300.webp 154w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_06-527x1024.webp 527w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_06-768x1493.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_06-6x12.webp 6w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_06-600x1167.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_06-150x292.webp 150w\" alt=\"\" width=\"1234\" height=\"2399\" \/><\/p>\n<p><strong>1. Pompe \u00e0 asphalte : R\u00e9sistante aux hautes temp\u00e9ratures et \u00e0 l'abrasion, elle transporte de mani\u00e8re stable des mat\u00e9riaux asphaltiques \u00e0 haute viscosit\u00e9.<\/strong><br \/>\n<strong>2. R\u00e9servoir d'huile hydraulique : Stocke l'huile et dissipe la chaleur pour assurer le bon fonctionnement du syst\u00e8me hydraulique.<\/strong><br \/>\n<strong>3. Tuyaux d'huile hydraulique : R\u00e9sistants \u00e0 la pression et \u00e0 la corrosion, ils transmettent efficacement la puissance hydraulique sans fuite.<\/strong><br \/>\n<strong>4. Filtre \u00e0 huile hydraulique : Filtre les impuret\u00e9s pour prolonger la dur\u00e9e de vie<\/strong><br \/>\n<strong>dur\u00e9e de vie des composants hydrauliques.<\/strong><br \/>\n<strong>5. Vannes hydrauliques : R\u00e9agissent rapidement et r\u00e9gulent avec pr\u00e9cision la direction et la pression du flux d'huile hydraulique.<\/strong><br \/>\n<strong>6. Vanne \u00e0 bille pneumatique : actionn\u00e9e par l'air, elle s'ouvre et se ferme rapidement et convient \u00e0 la commande automatique.<\/strong><br \/>\n<strong>7. Manom\u00e8tre : Affiche intuitivement la pression, facilitant la surveillance et le r\u00e9glage de la pression dans le pneumat-<\/strong><strong>syst\u00e8me ICE.<\/strong><br \/>\n<strong>8. Soupape de contre-pression\u00a0: Stabilise la pression et emp\u00eache\u00a0<\/strong><strong>reflux, assurant une r\u00e9partition uniforme et stable de l'asphalte,<\/strong><br \/>\n<strong>9. Filtre \u00e0 asphalte : \u00c9limine les impuret\u00e9s pour \u00e9viter les pannes dues au blocage des buses et des canalisations.<\/strong><br \/>\n<strong>10. Canalisation d'asphalte : R\u00e9sistant aux hautes temp\u00e9ratures et \u00e0 l'adh\u00e9rence, il r\u00e9duit la r\u00e9sistance et les r\u00e9sidus lors du transport de l'asphalte.<\/strong><br \/>\n<strong>11. Groupe de buses en acier inoxydable : R\u00e9sistant \u00e0 la corrosion et \u00e0 l'abrasion, il poss\u00e8de un angle de pulv\u00e9risation pr\u00e9cis et une zone de couverture uniforme.<\/strong><br \/>\n<strong>12. Unit\u00e9 de contr\u00f4le centrale : Permet un contr\u00f4le conjoint intelligent, permettant des op\u00e9rations d'\u00e9pandage pr\u00e9cises et efficaces.<\/strong><\/p>\n<h2 style=\"text-align: center;\">SYST\u00c8ME DE CHAUFFAGE INTELLIGENT \u00c0 TEMP\u00c9RATURE R\u00c9GUL\u00c9E<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7562\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_08.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08-131x300.webp 131w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08-446x1024.webp 446w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08-768x1762.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08-670x1536.webp 670w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08-5x12.webp 5w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08-600x1376.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_08-150x344.webp 150w\" alt=\"\" width=\"1234\" height=\"2830\" \/><\/p>\n<p><strong>1. Chauffage au diesel : Il poss\u00e8de une grande adaptabilit\u00e9 au carburant, une vitesse de chauffage rapide et une puissance de chauffage suffisante.<\/strong><br \/>\n<strong>2. Pompe \u00e0 huile thermoconductrice : Fonctionne de mani\u00e8re stable pour assurer la circulation efficace de l'huile thermoconductrice.<\/strong><br \/>\n<strong>3. Filtre \u00e0 huile thermoconducteur : Filtre les impuret\u00e9s pour prot\u00e9ger les composants essentiels du syst\u00e8me.<\/strong><br \/>\n<strong>4. Vanne \u00e0 trois voies pour huile caloporteuse\u00a0: Permet de basculer facilement entre les modes chauffage et maintien au chaud.<\/strong><br \/>\n<strong>5. Appareil de chauffage \u00e9lectrique : Propre et non polluant, avec un contr\u00f4le pr\u00e9cis de la temp\u00e9rature, il convient au pr\u00e9chauffage d'appoint.<\/strong><br \/>\n<strong>6. Serpentin chauffant dans le r\u00e9servoir : Permet un \u00e9change de chaleur uniforme, emp\u00eachant la carbonisation locale \u00e0 haute temp\u00e9rature de l'asphalte.<\/strong><br \/>\n<strong>7. Couche d'isolation thermique du r\u00e9servoir d'asphalte : Elle poss\u00e8de de bonnes performances d'isolation thermique, r\u00e9duisant la dissipation de chaleur et diminuant la consommation d'\u00e9nergie.<\/strong><\/p>\n<h2 style=\"text-align: center;\">CONCEPTION DES OP\u00c9RATIONS CENTR\u00c9ES SUR L'HUMAIN<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7563\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_10.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_10.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_10-217x300.webp 217w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_10-741x1024.webp 741w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_10-768x1062.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_10-9x12.webp 9w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_10-600x829.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_10-150x207.webp 150w\" alt=\"\" width=\"1234\" height=\"1706\" \/><\/p>\n<p><strong>1. \u00c9cran tactile intelligent : Il offre une interaction homme-machine pratique, avec un param\u00e9trage et une surveillance intuitifs.<\/strong><br \/>\n<strong>2. Console de commande manuelle : Elle offre des capacit\u00e9s d'urgence et de r\u00e9glage fin flexibles, s'adaptant aux sc\u00e9narios de construction complexes.<\/strong><br \/>\n<strong>3. Capteur de niveau de liquide \u00e0 bille flottante : Il poss\u00e8de une induction sensible et stable, refl\u00e9tant avec pr\u00e9cision la quantit\u00e9 d'asphalte restante.<\/strong><br \/>\n<strong>4. Indicateur de niveau de liquide : L'indicateur m\u00e9canique est clair et le niveau de liquide peut toujours \u00eatre v\u00e9rifi\u00e9 m\u00eame lorsque l'appareil est hors tension.<\/strong><br \/>\n<strong>5. Vanne \u00e0 bille de d\u00e9charge : Elle s'ouvre et se ferme en douceur avec une bonne \u00e9tanch\u00e9it\u00e9, emp\u00eachant les fuites d'asphalte.<\/strong><\/p>\n<h2 style=\"text-align: center;\">CORPS DE R\u00c9SERVOIR DURABLE ET R\u00c9SISTANT \u00c0 LA CORROSION<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7564\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_12.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_12.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_12-300x173.webp 300w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_12-768x443.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_12-18x10.webp 18w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_12-600x346.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_12-150x87.webp 150w\" alt=\"\" width=\"1234\" height=\"712\" \/><\/p>\n<p><strong>Acier au carbone r\u00e9sistant \u00e0 l'usure avec un rev\u00eatement anticorrosion double couche<\/strong><\/p>\n<h2 style=\"text-align: center;\">PROCESSUS DE PRODUCTION<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7565\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_14.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_14.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_14-163x300.webp 163w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_14-555x1024.webp 555w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_14-768x1417.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_14-7x12.webp 7w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_14-600x1107.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_14-150x277.webp 150w\" alt=\"\" width=\"1234\" height=\"2277\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7566\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_15.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15-119x300.webp 119w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15-407x1024.webp 407w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15-768x1931.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15-611x1536.webp 611w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15-5x12.webp 5w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15-600x1508.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_15-150x377.webp 150w\" alt=\"\" width=\"1234\" height=\"3102\" \/><\/p>\n<p><strong>1. Production et alimentation initiales<\/strong><br \/>\n<strong>2. Mise en forme initiale du corps du r\u00e9servoir<\/strong><br \/>\n<strong>3. T\u00eate du corps du char<\/strong><br \/>\n<strong>4. Montage du corps du char sur le ch\u00e2ssis<\/strong><br \/>\n<strong>5. Installation des accessoires tels que les buses de pulv\u00e9risation sur le ch\u00e2ssis. 6. Installation de l'unit\u00e9 de commande centrale.<\/strong><br \/>\n<strong>7. La partie sup\u00e9rieure du v\u00e9hicule est termin\u00e9e et l'assemblage d\u00e9taill\u00e9 est en cours.<\/strong><\/p>\n<h2 style=\"text-align: center;\">SC\u00c9NARIOS D'APPLICATION<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7567\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_17.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_17.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_17-167x300.webp 167w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_17-570x1024.webp 570w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_17-768x1379.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_17-7x12.webp 7w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_17-600x1078.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_17-150x269.webp 150w\" alt=\"\" width=\"1234\" height=\"2217\" \/><\/p>\n<h2 style=\"text-align: center;\">EMBALLAGE ET TRANSPORT<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7568\" src=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/%E6%B2%A5%E9%9D%92%E6%B4%92%E5%B8%83%E8%BD%A6%E8%AF%A6%E6%83%85%E9%A1%B5_19.webp\" sizes=\"(max-width: 1234px) 100vw, 1234px\" srcset=\"https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_19.webp 790w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_19-212x300.webp 212w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_19-724x1024.webp 724w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_19-768x1086.webp 768w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_19-8x12.webp 8w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_19-600x848.webp 600w, https:\/\/kailion.ltd\/wp-content\/uploads\/2026\/01\/\u6ca5\u9752\u6d12\u5e03\u8f66\u8be6\u60c5\u9875_19-150x212.webp 150w\" alt=\"\" width=\"1234\" height=\"1745\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>PRODUCT PARAMETERS Asphalt distributor 10000L SHACMAN project Descriptions Specifications Basic Overall dimensions(mm) 7930\u00d72550\u00d73550 curb weight(Kg) 9120 Loading capacity(Kg) 8970 Total<\/p>","protected":false},"featured_media":7605,"template":"","meta":[],"product_brand":[247],"product_cat":[375],"product_tag":[233,376,377,378],"class_list":{"0":"post-7601","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-shacman","7":"product_cat-asphalt-distributor","8":"product_tag-10000l","9":"product_tag-asphalt-distributor","10":"product_tag-bitumen-distributor-truck","11":"product_tag-bitumen-sprayer-truck","13":"first","14":"instock","15":"shipping-taxable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product\/7601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product\/7601\/revisions"}],"predecessor-version":[{"id":7871,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product\/7601\/revisions\/7871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/media\/7605"}],"wp:attachment":[{"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/media?parent=7601"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product_brand?post=7601"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product_cat?post=7601"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kailion.ltd\/fr\/wp-json\/wp\/v2\/product_tag?post=7601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}